{"id":586,"date":"2024-11-13T18:32:08","date_gmt":"2024-11-13T18:32:08","guid":{"rendered":"https:\/\/archive.terrazzo-usa.com\/?page_id=586"},"modified":"2026-07-02T14:42:23","modified_gmt":"2026-07-02T18:42:23","slug":"colors","status":"publish","type":"page","link":"https:\/\/archive.terrazzo-usa.com\/es\/colors\/","title":{"rendered":"Colores"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"586\" class=\"elementor elementor-586\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-6a8ef537 wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"6a8ef537\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-29a203f0 e-flex e-con-boxed e-con e-child\" data-id=\"29a203f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-767f57dc elementor-widget elementor-widget-heading\" data-id=\"767f57dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Paleta de colores<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-3310f65d wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"3310f65d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-447f8686 e-flex e-con-boxed e-con e-child\" data-id=\"447f8686\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1859d057 e-flex e-con-boxed e-con e-child\" data-id=\"1859d057\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34dae935 elementor-widget elementor-widget-heading\" data-id=\"34dae935\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explore nuestra amplia paleta de colores<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c335314 elementor-widget elementor-widget-heading\" data-id=\"6c335314\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Enlucido Terrazzo GraniTech, con m\u00e1s de 50 tonos distintos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-283ad6b6 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"283ad6b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para encontrar la combinaci\u00f3n perfecta para su espacio. Desde pasteles sutiles a tonos atrevidos, nuestra vibrante selecci\u00f3n le permite crear un ambiente acogedor o hacer una declaraci\u00f3n llamativa, asegurando que su espacio sea exclusivamente suyo. Deje que nuestra cambiante paleta de colores de escayola decorativa transporte sus sentidos a un destino que refleje su individualidad, o perm\u00edtanos combinar a la perfecci\u00f3n el tono que desee.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21850c9 elementor-widget elementor-widget-image\" data-id=\"21850c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result.webp\" class=\"attachment-full size-full wp-image-6352\" alt=\"\" srcset=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result.webp 1920w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-100x67.webp 100w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-780x520.webp 780w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-300x200.webp 300w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-768x512.webp 768w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-1024x683.webp 1024w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-1536x1024.webp 1536w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-18x12.webp 18w, https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/06\/terrazzo-granitech-foldable-brochure_result-150x100.webp 150w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-8a83760 wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"8a83760\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-c7a55f2 e-flex e-con-boxed e-con e-child\" data-id=\"c7a55f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-9e69aba e-flex e-con-boxed e-con e-child\" data-id=\"9e69aba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62d79c7 elementor-widget elementor-widget-heading\" data-id=\"62d79c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Carta de colores medios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c51bf8 elementor-skin-carousel elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"3c51bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;4&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:32,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"ABALONE-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/ABALONE-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"abingdon-putty\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/abingdon-putty.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"acadia-verde\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/acadia-green.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"antiguan-sky\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/antiguan-sky.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"bleekere-beige\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/bleekere-beige.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"blue-lake\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/blue-lake.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"nota azul\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/blue-note.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"BRICK-RED-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/BRICK-RED-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"broadstreet-beige\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/broadstreet-beige-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"BROOKLINE-BEIGE-2\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/BROOKLINE-BEIGE-2.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"camello\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/camel.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"camuflaje\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/camouflage.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"chelsea-gray\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/chelsea-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"de-catur-buff\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/de-catur-buff.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"desierto-tan\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/desert-tan.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"dior-gray\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/dior-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"\u03b5\u03bb\u03b5\u03c0\u03b7\u03b1\u03bd\u03c4-\u03b3\u03c1\u03b1\u03c5\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/\u03b5\u03bb\u03b5\u03c0\u03b7\u03b1\u03bd\u03c4-\u03b3\u03c1\u03b1\u03c5.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"g\u00e9nesis-blanco\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/genesis-white.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"golden-manila\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/golden-manila.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gran-verde\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/great-green.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"green-meadowsn\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/green-meadowsn.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gaviota gris\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/gull-wind-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gris puerto\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/harbor-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"azul avellana\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/hazy-blue.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"matiz-violeta\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/hint-of-violet.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"helado de malva\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/iced-mauve.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"lafayette-green\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/lafayette-green.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gris monta\u00f1a\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/mt.-rainer-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"oro m\u00edstico\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/mystic-gold.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"negro\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/negro.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"normand\u00eda\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/normandy.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"ola-praire\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/ola-praire.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"rama de olivo-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/olive-branch-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"ozark-shadows\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/ozark-shadows.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"verde p\u00e1lido\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/peale-green.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gris paloma\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/pigeon-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"portland-gray\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/portland-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"acera-gris\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/sidewalk-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"silver-fox\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/silver-fox.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"siver-spring\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/siver-spring.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"tate-oliva\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/tate-olive.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"skinroze medium_result\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/09\/skinroze-medium_result.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"c\u00farcuma\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/turmeric.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"valley-brown-farge\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/valley-brown-farge.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"VICTORIANO-MAUVE\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/VICTORIAN-MAUVE.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"waterbury-verde\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/waterbury-green.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"hormig\u00f3n h\u00famedo\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/wet-concrete.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"ballena-gris\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/whale-gray.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"WHITE-SNOW\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/WHITE-SNOW.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"aguas bravas\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/white-water.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"arroz salvaje\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/wild-rice.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"lago de invierno\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/winter-lake.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-73b27df wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"73b27df\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-9dd062c e-flex e-con-boxed e-con e-child\" data-id=\"9dd062c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-121d0df e-flex e-con-boxed e-con e-child\" data-id=\"121d0df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08033f0 elementor-widget elementor-widget-heading\" data-id=\"08033f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Carta de colores finos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc8148 elementor-skin-carousel elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"5dc8148\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;4&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:32,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"abalone-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/abalone-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"abingdon-putty-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/abingdon-putty-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"acadia-greenf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/acadia-greenf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"antiguan-skyf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/antiguan-skyf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"bleeker-beigef\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/bleeker-beigef.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"blue-lakef\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/blue-lakef.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"azul-ntoe-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/blue-ntoe-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"BRICK-RED-F\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/BRICK-RED-F.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"broadstreet-beigef\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/broadstreet-beigef.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"brookline-beige-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/brookline-beige-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"camel-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/camel-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"camuflaje-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/camouflage-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"chelsea-grayf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/chelsea-grayf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"de-catur-buff-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/de-catur-buff-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"desierto-tan-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/desert-tan-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"dior-gris-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/dior-gray-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"elefante-gris-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/elephant-gray-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"g\u00e9nesis-blancof\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/genesis-whitef.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"golden-manilaf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/golden-manilaf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gran-verdef\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/great-greenf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"green-meadows-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/green-meadows-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gaviota-gris-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/gull-wind-gray-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"puerto-gris-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/harbor-gray-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"azul avellana-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/hazy-blue-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"hint-of-violet-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/hint-of-violet-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"helado-malva-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/iced-mauve-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"lafayette-verde-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/lafayette-green-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"mt.-rainer-grayf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/mt.-rainer-grayf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"mystic-goldf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/mystic-goldf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"negro-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/negro-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"normandy-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/normandy-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"ola-prairef\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/ola-prairef.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"rama de olivof\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/olive-branchf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"ozark-sombras-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/ozark-shadows-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"peale-verde-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/peale-green-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"gris paloma-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/pigeon-gray-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"portland-gray-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/portland-gray-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"acera-gris-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/sidewalk-gray-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"silver-foxf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/silver-foxf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"silver-springf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/silver-springf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"tate-olive-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/tate-olive-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"skin roze fine_result\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/09\/skin-roze-fine_result-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"c\u00farcuma-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/turmeric-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"valley-brown-farge-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/valley-brown-farge-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"victorian-mauvef\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/victorian-mauvef.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"waterbury-verde-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/waterbury-green-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"ballena-grisf\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/whale-grayf.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"WHITE-SNOW-2\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/WHITE-SNOW-2.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"aguas bravas-f\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/white-water-f.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"wild-ricef\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/wild-ricef.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"lago-de-invierno-1\" data-background=\"https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2024\/11\/winter-lake-1.webp\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-41474d2 wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"41474d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-a95fc22 e-flex e-con-boxed e-con e-child\" data-id=\"a95fc22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-22d7959 e-flex e-con-boxed e-con e-child\" data-id=\"22d7959\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b307287 elementor-widget elementor-widget-heading\" data-id=\"b307287\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Carta de colores Microterrazzo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dec00c9 elementor-skin-carousel elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"dec00c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:32,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"microterrazzo-600q_resultado\" style=\"background-image: url(&#039;https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2025\/07\/microterrazzo-600q_result-1.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Zambia_-_text\" style=\"background-image: url(&#039;https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2026\/07\/Zambia_-_text-1.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Roma_-_text\" style=\"background-image: url(&#039;https:\/\/archive.terrazzo-usa.com\/wp-content\/uploads\/2026\/07\/Roma_-_text-1.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-56ca8b3 e-flex e-con-boxed e-con e-child\" data-id=\"56ca8b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c603957 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"c603957\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><strong>Microterrazzo 600Q<\/strong>\u00a0presenta una llamativa mezcla de \u00e1ridos de cuarzo negro y beige...<strong>actualmente el \u00fanico acabado disponible<\/strong>\u00a0de la colecci\u00f3n. Aunque el fondo de nuestra firma es blanco, el color se puede personalizar totalmente mediante el bot\u00f3n\u00a0<strong>Sistema de pigmentos TERRAZZO GraniTech Medium<\/strong>El tono de base se adapta a la est\u00e9tica y la visi\u00f3n \u00fanica de su proyecto. Para un contraste \u00f3ptimo, recomendamos seleccionar un fondo claro para realzar la definici\u00f3n natural del \u00e1rido.<\/p><p style=\"font-weight: 400;\">The Microterrazzo collection expanded with two distinctive new finishes:<\/p><ul style=\"font-weight: 400;\"><li><strong>Microterrazzo Roma: una textura c\u00e1lida y atemporal que evoca las superficies arquitect\u00f3nicas cl\u00e1sicas<\/strong><\/li><li><strong>Microterrazzo Zambia: una mezcla terrosa y expresiva inspirada en la piedra natural y la arcilla<\/strong><\/li><\/ul><p style=\"font-weight: 400;\">Para solicitar acceso anticipado u obtener m\u00e1s informaci\u00f3n sobre las pr\u00f3ximas combinaciones de colores, <b>contacte con nuestro equipo hoy mismo<\/b>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1d4a4 elementor-align-center elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"2b1d4a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/archive.terrazzo-usa.com\/es\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacte con nosotros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Color Palette Explore our expansive color palette Terrazzo GraniTech plaster, offering over 50 diverse shades To find the perfect match<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-586","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/archive.terrazzo-usa.com\/es\/wp-json\/wp\/v2\/pages\/586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archive.terrazzo-usa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/archive.terrazzo-usa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/archive.terrazzo-usa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archive.terrazzo-usa.com\/es\/wp-json\/wp\/v2\/comments?post=586"}],"version-history":[{"count":0,"href":"https:\/\/archive.terrazzo-usa.com\/es\/wp-json\/wp\/v2\/pages\/586\/revisions"}],"wp:attachment":[{"href":"https:\/\/archive.terrazzo-usa.com\/es\/wp-json\/wp\/v2\/media?parent=586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}